{"id":1532,"date":"2011-09-14T09:52:08","date_gmt":"2011-09-14T08:52:08","guid":{"rendered":"http:\/\/www.agustinbarahona.com\/blog\/?p=1532"},"modified":"2014-04-13T17:54:50","modified_gmt":"2014-04-13T16:54:50","slug":"justicia-es","status":"publish","type":"post","link":"https:\/\/www.agustinbarahona.com\/blog\/justicia-es\/","title":{"rendered":"Justicia es&#8230;"},"content":{"rendered":"<div style=\"background-color: #cc8; padding: 25px; margin: -7px;\">\n<p><img decoding=\"async\" alt=\"File:Plato Pio-Clemetino Inv305.jpg\" src=\"http:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/d\/da\/Plato_Pio-Clemetino_Inv305.jpg\/395px-Plato_Pio-Clemetino_Inv305.jpg\" width=\"430\" \/><\/p>\n<p><em><span style=\"font-family: 'Times New Roman'; font-size: 115%;\">\u00abJusticia es dar a cada uno lo que le corresponde seg\u00fan su naturaleza.\u00bb [Plat\u00f3n]<\/span><\/em><\/p>\n<p>\u00abCreo que todo el mundo aceptar\u00eda con total facilidad que se recortara en Educaci\u00f3n si previamente se mostrara y demostrara que se ha recortado anteriormente los sueldos y aumentado los horarios presenciales a todos los pol\u00edticos y prescindido de tantas cosas completamente in\u00fatiles (como los traductores en un pa\u00eds con lengua com\u00fan). Lo \u00faltimo en lo que deber\u00eda recortarse es en una actividad para cuyo ejercicio se requiere una alta cualificaci\u00f3n y que es garant\u00eda social de futuro.\u00a0 Sea la que sea.<\/p>\n<p>Ser\u00eda conveniente que en Espa\u00f1a se adquiriese la costumbre de citar las normas ley\u00e9ndolas exactamente en los medios de comunicaci\u00f3n. Si no cualquiera que pretenda citarlas de memoria puede equivocarse estrepitosamente. Me gustar\u00eda que se citase exactamente lo que dice la norma que presuntamente permite que sea legal el aumento de horas presente a los profesores y de d\u00f3nde se deben quitar. Quiz\u00e1 podr\u00eda haber sorpresas. Es s\u00f3lo un consejo general. De otro modo, podr\u00eda discutirse en vano.\u00bb [Agust\u00edn Barahona]<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00abJusticia es dar a cada uno lo que le corresponde seg\u00fan su naturaleza.\u00bb [Plat\u00f3n] \u00abCreo que todo el mundo aceptar\u00eda con total facilidad que se recortara en Educaci\u00f3n si previamente se mostrara y demostrara que se ha recortado anteriormente los sueldos y aumentado los horarios presenciales a todos los pol\u00edticos y prescindido de tantas cosas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9,16],"tags":[18,43,32],"class_list":["post-1532","post","type-post","status-publish","format-standard","hentry","category-escritos-en-facebook","category-humanismo","tag-cultura","tag-filosofia","tag-justicia"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.agustinbarahona.com\/blog\/wp-json\/wp\/v2\/posts\/1532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agustinbarahona.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agustinbarahona.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agustinbarahona.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agustinbarahona.com\/blog\/wp-json\/wp\/v2\/comments?post=1532"}],"version-history":[{"count":7,"href":"https:\/\/www.agustinbarahona.com\/blog\/wp-json\/wp\/v2\/posts\/1532\/revisions"}],"predecessor-version":[{"id":1540,"href":"https:\/\/www.agustinbarahona.com\/blog\/wp-json\/wp\/v2\/posts\/1532\/revisions\/1540"}],"wp:attachment":[{"href":"https:\/\/www.agustinbarahona.com\/blog\/wp-json\/wp\/v2\/media?parent=1532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agustinbarahona.com\/blog\/wp-json\/wp\/v2\/categories?post=1532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agustinbarahona.com\/blog\/wp-json\/wp\/v2\/tags?post=1532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}